{"id":121,"name":"ken","url":"http:\/\/www.cnzhenfa.com","description":"","link":"http:\/\/www.travelthrifters.com\/blog\/author\/ken\/","slug":"ken","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0c74c9f589d939496dabdd4c10ab46972e6de23849f2136d2e8de6a25744e31e?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0c74c9f589d939496dabdd4c10ab46972e6de23849f2136d2e8de6a25744e31e?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0c74c9f589d939496dabdd4c10ab46972e6de23849f2136d2e8de6a25744e31e?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.travelthrifters.com\/blog\/wp-json\/wp\/v2\/users\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.travelthrifters.com\/blog\/wp-json\/wp\/v2\/users"}]}}