{"id":113,"name":"delbert","url":"http:\/\/www.eastasiavalves.com","description":"","link":"http:\/\/www.travelthrifters.com\/blog\/author\/delbert\/","slug":"delbert","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1e805124f4e9a8c1d2eca41b8c75e48417cc3a3d719a0498df4adfca50e88a90?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1e805124f4e9a8c1d2eca41b8c75e48417cc3a3d719a0498df4adfca50e88a90?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1e805124f4e9a8c1d2eca41b8c75e48417cc3a3d719a0498df4adfca50e88a90?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"http:\/\/www.travelthrifters.com\/blog\/wp-json\/wp\/v2\/users\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.travelthrifters.com\/blog\/wp-json\/wp\/v2\/users"}]}}